

{"id":2487,"date":"2016-12-15T14:45:04","date_gmt":"2016-12-15T14:45:04","guid":{"rendered":"http:\/\/metal.loria.fr\/?p=2487"},"modified":"2016-12-15T14:45:04","modified_gmt":"2016-12-15T14:45:04","slug":"presentation-de-metal-aux-recteurs-duniversites-technologiques-du-mexique","status":"publish","type":"post","link":"https:\/\/metal.loria.fr\/fr\/presentation-de-metal-aux-recteurs-duniversites-technologiques-du-mexique\/","title":{"rendered":"Pr\u00e9sentation de METAL aux recteurs d\u2019Universit\u00e9s Technologiques du Mexique"},"content":{"rendered":"<p>A l\u2019occasion des 50 ans des IUT en France, des 15 ans du programme MEXPROTEC et des 25 ans des Universit\u00e9s Technologiques (UT) mexicaines, le Loria, la Ville de Nancy, l\u2019IUT Charlemagne, Nancy Num\u00e9rique et Lor\u2019n\u2019Tech ont accueilli nos partenaires internationaux pour leur faire d\u00e9couvrir la place du num\u00e9rique en Lorraine le 1<sup>er<\/sup> d\u00e9cembre 2016.<\/p>\n<p>Anne Boyer, a pr\u00e9sent\u00e9 METAL aux recteurs lors d\u2019une matin\u00e9e d\u2019\u00e9changes, de d\u00e9monstrations et de pr\u00e9sentations de travaux de recherche organis\u00e9e par les membres de l\u2019\u00e9quipe Synalp.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l\u2019occasion des 50 ans des IUT en France, des 15 ans du programme MEXPROTEC et des 25 ans des Universit\u00e9s Technologiques (UT) mexicaines, le Loria, la Ville de Nancy, l\u2019IUT Charlemagne, Nancy Num\u00e9rique et Lor\u2019n\u2019Tech ont accueilli nos partenaires internationaux pour leur faire d\u00e9couvrir la place du num\u00e9rique en\u2026<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/metal.loria.fr\/fr\/presentation-de-metal-aux-recteurs-duniversites-technologiques-du-mexique\/\"><span>En savoir +<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n","protected":false},"author":1990,"featured_media":2488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[35],"tags":[],"class_list":["post-2487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/posts\/2487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/users\/1990"}],"replies":[{"embeddable":true,"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/comments?post=2487"}],"version-history":[{"count":0,"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/posts\/2487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/media\/2488"}],"wp:attachment":[{"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/media?parent=2487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/categories?post=2487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metal.loria.fr\/fr\/wp-json\/wp\/v2\/tags?post=2487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}